{"id":36627,"date":"2023-08-31T15:18:05","date_gmt":"2023-08-31T07:18:05","guid":{"rendered":"https:\/\/chinesemusics.com\/?p=36627"},"modified":"2023-09-06T21:21:55","modified_gmt":"2023-09-06T13:21:55","slug":"%e9%ab%98%e5%8d%9a%e6%96%87","status":"publish","type":"post","link":"https:\/\/chinesemusics.com\/zh_cn\/2023\/08\/31\/%e9%ab%98%e5%8d%9a%e6%96%87\/","title":{"rendered":"\u9ad8\u535a\u6587"},"content":{"rendered":"<p class=\"has-medium-font-size wp-block-paragraph\">\u9ad8\u535a\u6587\uff08\u8a55\u5f48\uff09\uff0c\u570b\u5bb6\u4e00\u7d1a\u6f14\u54e1\uff0c\u4e2d\u570b\u66f2\u85dd\u5bb6\u5354\u6703\u7406\u4e8b\uff0c\u4e0a\u6d77\u8a55\u5f48\u5718\u526f\u5718\u9577\uff0c\u4e0a\u6d77\u5927\u5b78\u5ba2\u5ea7\u6559\u6388\u3002\u5f48\u8a5e\u300a\u73cd\u73e0\u5854\u300b\u201c\u9b4f\u201d\u201c\u6c88\u201d\u201c\u859b\u201d\u4e09\u5927\u6d41\u6d3e\u50b3\u627f\u4eba\u3002\u66fe\u591a\u6b21\u69ae\u7372\u4e2d\u570b\u66f2\u85dd\u201c\u7cbe\u54c1\u7bc0\u76ee\u734e\u201d\u548c\u201c\u512a\u79c0\u7bc0\u76ee\u734e\u201d\u7b49\u69ae\u8b7d\u3002<br><br><\/p>","protected":false},"excerpt":{"rendered":"<p>\u9ad8\u535a\u6587\uff08\u8a55\u5f48\uff09\uff0c\u570b\u5bb6\u4e00\u7d1a\u6f14\u54e1\uff0c\u4e2d\u570b\u66f2\u85dd\u5bb6\u5354\u6703\u7406\u4e8b\uff0c\u4e0a\u6d77\u8a55\u5f48\u5718\u526f\u5718\u9577\uff0c\u4e0a\u6d77\u5927\u5b78\u5ba2\u5ea7\u6559\u6388\u3002\u5f48\u8a5e\u300a\u73cd\u73e0\u5854\u300b\u201c\u9b4f\u201d\u201c\u6c88\u201d\u201c\u859b\u201d\u4e09\u5927\u6d41\u6d3e\u50b3\u627f\u4eba\u3002\u66fe\u591a\u6b21\u69ae\u7372\u4e2d\u570b\u66f2\u85dd\u201c\u7cbe\u54c1\u7bc0\u76ee\u734e\u201d\u548c\u201c\u512a\u79c0\u7bc0\u76ee\u734e\u201d\u7b49\u69ae\u8b7d\u3002<\/p>","protected":false},"author":27,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,162],"tags":[],"class_list":["post-36627","post","type-post","status-publish","format-standard","hentry","category-guqin","category-performer"],"_links":{"self":[{"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/posts\/36627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/comments?post=36627"}],"version-history":[{"count":1,"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/posts\/36627\/revisions"}],"predecessor-version":[{"id":36628,"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/posts\/36627\/revisions\/36628"}],"wp:attachment":[{"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/media?parent=36627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/categories?post=36627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chinesemusics.com\/zh_cn\/wp-json\/wp\/v2\/tags?post=36627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}