{"id":35385,"date":"2023-08-31T16:55:23","date_gmt":"2023-08-31T08:55:23","guid":{"rendered":"https:\/\/chinesemusics.com\/?page_id=35385"},"modified":"2023-09-05T14:51:15","modified_gmt":"2023-09-05T06:51:15","slug":"p-guqin","status":"publish","type":"page","link":"https:\/\/chinesemusics.com\/en_us\/info-db\/performers\/p-guqin\/","title":{"rendered":"\u53e4\u7434\u6f14\u594f\u8005"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"35385\" class=\"elementor elementor-35385\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-587b56e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"587b56e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8bfa4ca\" data-id=\"8bfa4ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cfca35 elementor-widget elementor-widget-heading\" data-id=\"7cfca35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u53e4\u7434\u6f14\u594f\u5bb6 -\nGuqin Performers<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20a5a1fd elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"20a5a1fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-212013c1\" data-id=\"212013c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1af46267 elementor-posts--thumbnail-none elementor-widget__width-initial elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"1af46267\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35889 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/35889\/\" >\n\t\t\t\t\u9f94\u5e7d\u862d\u00a0(GONG You-lan)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/35889\/\" aria-label=\"Read more about \u9f94\u5e7d\u862d\u00a0(GONG You-lan)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35974 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%be%94%e4%b8%80\/\" >\n\t\t\t\t\u9f94\u4e00\u00a0(GONG Yi)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%be%94%e4%b8%80\/\" aria-label=\"Read more about \u9f94\u4e00\u00a0(GONG Yi)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35896 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%be%8d%e7%90%b4%e8%88%ab\/\" >\n\t\t\t\t\u9f8d\u7434\u822b\u00a0(LONG Qin-fang)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%be%8d%e7%90%b4%e8%88%ab\/\" aria-label=\"Read more about \u9f8d\u7434\u822b\u00a0(LONG Qin-fang)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35928 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e9%9b%aa%e8%bc%9d\/\" >\n\t\t\t\t\u9ec3\u96ea\u8f1d\u00a0(HUANG Xue-hui)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e9%9b%aa%e8%bc%9d\/\" aria-label=\"Read more about \u9ec3\u96ea\u8f1d\u00a0(HUANG Xue-hui)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36601 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e6%b0%b8%e6%98%8e\/\" >\n\t\t\t\t\u9ec3\u6c38\u660e\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e6%b0%b8%e6%98%8e\/\" aria-label=\"Read more about \u9ec3\u6c38\u660e\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36621 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e6%a2%85\/\" >\n\t\t\t\t\u9ec3\u6885\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e6%a2%85\/\" aria-label=\"Read more about \u9ec3\u6885\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36589 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e5%be%b7%e6%ba%90\/\" >\n\t\t\t\t\u9ec3\u5fb7\u6e90\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e5%be%b7%e6%ba%90\/\" aria-label=\"Read more about \u9ec3\u5fb7\u6e90\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36609 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e5%be%b7%e6%ac%a3\/\" >\n\t\t\t\t\u9ec3\u5fb7\u6b23\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e5%be%b7%e6%ac%a3\/\" aria-label=\"Read more about \u9ec3\u5fb7\u6b23\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36637 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e5%81%89%e9%88%9e\/\" >\n\t\t\t\t\u9ec3\u5049\u921e\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%bb%83%e5%81%89%e9%88%9e\/\" aria-label=\"Read more about \u9ec3\u5049\u921e\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36619 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%ab%98%e5%ae%87\/\" >\n\t\t\t\t\u9ad8\u5b87\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%ab%98%e5%ae%87\/\" aria-label=\"Read more about \u9ad8\u5b87\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36627 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%ab%98%e5%8d%9a%e6%96%87\/\" >\n\t\t\t\t\u9ad8\u535a\u6587\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%ab%98%e5%8d%9a%e6%96%87\/\" aria-label=\"Read more about \u9ad8\u535a\u6587\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35910 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%ab%98%e4%bb%b2%e9%88%9e\/\" >\n\t\t\t\t\u9ad8\u4ef2\u921e\u00a0(GAO Zhong-jun)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%ab%98%e4%bb%b2%e9%88%9e\/\" aria-label=\"Read more about \u9ad8\u4ef2\u921e\u00a0(GAO Zhong-jun)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35881 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%a6%ac%e6%9d%b0\/\" >\n\t\t\t\t\u99ac\u6770\u00a0(MA Jie)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%a6%ac%e6%9d%b0\/\" aria-label=\"Read more about \u99ac\u6770\u00a0(MA Jie)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35865 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%a6%ac%e5%a3%bd%e6%b4%9b\/\" >\n\t\t\t\t\u99ac\u58fd\u6d1b\u00a0(MA Shou-luo)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%a6%ac%e5%a3%bd%e6%b4%9b\/\" aria-label=\"Read more about \u99ac\u58fd\u6d1b\u00a0(MA Shou-luo)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35952 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%a1%a7%e6%a2%85%e7%be%b9\/\" >\n\t\t\t\t\u9867\u6885\u7fb9\u00a0(GU Mei-geng)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%a1%a7%e6%a2%85%e7%be%b9\/\" aria-label=\"Read more about \u9867\u6885\u7fb9\u00a0(GU Mei-geng)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36623 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b8%e7%ac%91%e5%a7%bf\/\" >\n\t\t\t\t\u9678\u7b11\u59ff\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b8%e7%ac%91%e5%a7%bf\/\" aria-label=\"Read more about \u9678\u7b11\u59ff\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35871 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e9%9b%af\/\" >\n\t\t\t\t\u9673\u96ef\u00a0(CHEN Wen)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e9%9b%af\/\" aria-label=\"Read more about \u9673\u96ef\u00a0(CHEN Wen)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35912 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e9%96%b1%e8%81%b0\/\" >\n\t\t\t\t\u9673\u95b1\u8070\u00a0(CHEN Yue-cong)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e9%96%b1%e8%81%b0\/\" aria-label=\"Read more about \u9673\u95b1\u8070\u00a0(CHEN Yue-cong)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35904 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e9%95%b7%e6%9e%97\/\" >\n\t\t\t\t\u9673\u9577\u6797\u00a0(CHEN Chang-lin)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e9%95%b7%e6%9e%97\/\" aria-label=\"Read more about \u9673\u9577\u6797\u00a0(CHEN Chang-lin)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35908 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e7%86%99%e7%8f%b5\/\" >\n\t\t\t\t\u9673\u7199\u73f5\u00a0(CHEN Xi-cheng)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e7%86%99%e7%8f%b5\/\" aria-label=\"Read more about \u9673\u7199\u73f5\u00a0(CHEN Xi-cheng)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36591 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e6%88%90%e6%b8%a4\/\" >\n\t\t\t\t\u9673\u6210\u6e24\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e6%88%90%e6%b8%a4\/\" aria-label=\"Read more about \u9673\u6210\u6e24\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36593 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e5%9c%8b%e8%88%88\/\" >\n\t\t\t\t\u9673\u570b\u8208\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e5%9c%8b%e8%88%88\/\" aria-label=\"Read more about \u9673\u570b\u8208\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36597 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e5%9c%8b%e7%87%88\/\" >\n\t\t\t\t\u9673\u570b\u71c8\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%99%b3%e5%9c%8b%e7%87%88\/\" aria-label=\"Read more about \u9673\u570b\u71c8\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36571 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%8d%be%e4%b9%8b%e5%b2%b3\/\" >\n\t\t\t\t\u937e\u4e4b\u5cb3\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%8d%be%e4%b9%8b%e5%b2%b3\/\" aria-label=\"Read more about \u937e\u4e4b\u5cb3\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35853 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%87%91%e6%b2%bb%e4%b8%ad\/\" >\n\t\t\t\t\u91d1\u6cbb\u4e2d\u00a0(JIN Zhi-zhong)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%87%91%e6%b2%bb%e4%b8%ad\/\" aria-label=\"Read more about \u91d1\u6cbb\u4e2d\u00a0(JIN Zhi-zhong)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35877 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%84%ad%e7%8f%89%e4%b8%ad\/\" >\n\t\t\t\t\u912d\u73c9\u4e2d\u00a0(ZHENG Min-zhong)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%84%ad%e7%8f%89%e4%b8%ad\/\" aria-label=\"Read more about \u912d\u73c9\u4e2d\u00a0(ZHENG Min-zhong)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35885 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%83%ad%e5%90%8c%e7%94%ab\/\" >\n\t\t\t\t\u90ed\u540c\u752b\u00a0(GUO Tong-fu)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e9%83%ad%e5%90%8c%e7%94%ab\/\" aria-label=\"Read more about \u90ed\u540c\u752b\u00a0(GUO Tong-fu)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36585 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%b6%99%e7%87%81\/\" >\n\t\t\t\t\u8d99\u71c1\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%b6%99%e7%87%81\/\" aria-label=\"Read more about \u8d99\u71c1\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36579 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%b6%99%e6%96%87%e6%80%a1\/\" >\n\t\t\t\t\u8d99\u6587\u6021\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%b6%99%e6%96%87%e6%80%a1\/\" aria-label=\"Read more about \u8d99\u6587\u6021\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35980 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%b6%99%e5%ae%b6%e7%8f%8d\/\" >\n\t\t\t\t\u8d99\u5bb6\u73cd\u00a0(ZHAO Jia-zhen)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%b6%99%e5%ae%b6%e7%8f%8d\/\" aria-label=\"Read more about \u8d99\u5bb6\u73cd\u00a0(ZHAO Jia-zhen)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35849 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%ac%9d%e5%b0%8e%e7%a7%80\/\" >\n\t\t\t\t\u8b1d\u5c0e\u79c0\u00a0(ZIE Dao-xiu)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%ac%9d%e5%b0%8e%e7%a7%80\/\" aria-label=\"Read more about \u8b1d\u5c0e\u79c0\u00a0(ZIE Dao-xiu)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35924 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%ac%9d%e5%ad%9d%e8%8b%b9\/\" >\n\t\t\t\tXIE Xiao-ping\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%ac%9d%e5%ad%9d%e8%8b%b9\/\" aria-label=\"Read more about \u8b1d\u5b5d\u82f9\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35938 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%ac%9d%e4%bf%8a%e4%bb%81\/\" >\n\t\t\t\tTSE Chun-yan\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%ac%9d%e4%bf%8a%e4%bb%81\/\" aria-label=\"Read more about \u8b1d\u4fca\u4ec1\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35875 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%a9%b9%e6%be%82%e7%a7%8b\/\" >\n\t\t\t\t\u8a79\u6f82\u79cb\u00a0(ZHAN Cheng-qiu)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%a9%b9%e6%be%82%e7%a7%8b\/\" aria-label=\"Read more about \u8a79\u6f82\u79cb\u00a0(ZHAN Cheng-qiu)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35922 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%a8%b1%e5%81%a5\/\" >\n\t\t\t\tXU Jian\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%a8%b1%e5%81%a5\/\" aria-label=\"Read more about \u8a31\u5065\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36641 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%a3%b4%e9%87%91%e5%af%b6\/\" >\n\t\t\t\t\u88f4\u91d1\u5bf6\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%a3%b4%e9%87%91%e5%af%b6\/\" aria-label=\"Read more about \u88f4\u91d1\u5bf6\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35966 post type-post status-publish format-standard hentry category-guqin category-performer category-pipa\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%a1%9b%e4%bb%b2%e6%a8%82\/\" >\n\t\t\t\t\u885b\u4ef2\u6a02 (Wei Chong Loh)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%a1%9b%e4%bb%b2%e6%a8%82\/\" aria-label=\"Read more about \u885b\u4ef2\u6a02 (Wei Chong Loh)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35839 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%98%87%e6%80%9d%e6%a3%a3\/\" >\n\t\t\t\t\u8607\u601d\u68e3\u00a0(SOU Si-tai)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%98%87%e6%80%9d%e6%a3%a3\/\" aria-label=\"Read more about \u8607\u601d\u68e3\u00a0(SOU Si-tai)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35968 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%94%a1%e5%be%b7%e5%85%81\/\" >\n\t\t\t\tTSAR Teh-yun\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%94%a1%e5%be%b7%e5%85%81\/\" aria-label=\"Read more about \u8521\u5fb7\u5141\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36595 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%8e%8a%e6%b4%97\/\" >\n\t\t\t\t\u838a\u6d17\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%8e%8a%e6%b4%97\/\" aria-label=\"Read more about \u838a\u6d17\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36565 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%8c%85%e6%af%85\/\" >\n\t\t\t\t\u8305\u6bc5\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%8c%85%e6%af%85\/\" aria-label=\"Read more about \u8305\u6bc5\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36561 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%8c%83%e7%ab%8b%e7%a9%8e\/\" >\n\t\t\t\t\u8303\u7acb\u7a4e\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%8c%83%e7%ab%8b%e7%a9%8e\/\" aria-label=\"Read more about \u8303\u7acb\u7a4e\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35847 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%83%a5%e6%a1%90%e8%8f%af\/\" >\n\t\t\t\tXU Tong-hua\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e8%83%a5%e6%a1%90%e8%8f%af\/\" aria-label=\"Read more about \u80e5\u6850\u83ef\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35836 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%ae%a1%e5%b9%b3%e6%b9%96\/\" >\n\t\t\t\t\u7ba1\u5e73\u6e56\u00a0(GUAN Ping-hu)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%ae%a1%e5%b9%b3%e6%b9%96\/\" aria-label=\"Read more about \u7ba1\u5e73\u6e56\u00a0(GUAN Ping-hu)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35964 post type-post status-publish format-standard hentry category-guqin category-performer category-pipa\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%a8%8b%e5%8d%88%e5%98%89\/\" >\n\t\t\t\t\u7a0b\u5348\u5609\u00a0(CHENG Wu-jia)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%a8%8b%e5%8d%88%e5%98%89\/\" aria-label=\"Read more about \u7a0b\u5348\u5609\u00a0(CHENG Wu-jia)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35879 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%9b%a7%e5%ae%b6%e7%82%b3\/\" >\n\t\t\t\t\u76e7\u5bb6\u70b3\u00a0(LO Ka-ping)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%9b%a7%e5%ae%b6%e7%82%b3\/\" aria-label=\"Read more about \u76e7\u5bb6\u70b3\u00a0(LO Ka-ping)\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-35894 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%8e%8b%e8%bf%aa\/\" >\n\t\t\t\t\u738b\u8fea\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%8e%8b%e8%bf%aa\/\" aria-label=\"Read more about \u738b\u8fea\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36567 post type-post status-publish format-standard hentry category-guqin category-performer\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%8e%8b%e7%a9%8e%e8%8b%91\/\" >\n\t\t\t\t\u738b\u7a4e\u82d1\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/chinesemusics.com\/en_us\/2023\/08\/31\/%e7%8e%8b%e7%a9%8e%e8%8b%91\/\" aria-label=\"Read more about \u738b\u7a4e\u82d1\" tabindex=\"-1\" >\n\t\t\tPersonal  Profile \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"3\" data-next-page=\"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages\/35385\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span class=\"page-numbers prev\">&laquo; Previous<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages\/35385\/page\/2\/\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages\/35385\/page\/3\/\"><span class=\"elementor-screen-only\">Page<\/span>3<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages\/35385\/page\/2\/\">Next &raquo;<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u53e4\u7434\u6f14\u594f\u5bb6 &#8211; Guqin Performers<\/p>","protected":false},"author":27,"featured_media":0,"parent":5387,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-35385","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages\/35385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/comments?post=35385"}],"version-history":[{"count":23,"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages\/35385\/revisions"}],"predecessor-version":[{"id":36558,"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages\/35385\/revisions\/36558"}],"up":[{"embeddable":true,"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/pages\/5387"}],"wp:attachment":[{"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/media?parent=35385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}