{"id":10,"count":50,"description":"","link":"https:\/\/chinesemusics.com\/en_us\/category\/performer\/guzheng\/","name":"\u53e4\u7b8f","slug":"guzheng","taxonomy":"category","parent":162,"meta":[],"_links":{"self":[{"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/categories\/162"}],"wp:post_type":[{"href":"https:\/\/chinesemusics.com\/en_us\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}